{"id":89796,"date":"2026-03-17T14:04:48","date_gmt":"2026-03-17T17:04:48","guid":{"rendered":"https:\/\/lavaca.org\/trinchera\/?p=89796"},"modified":"2026-04-09T11:58:47","modified_gmt":"2026-04-09T14:58:47","slug":"marzo-2026-mu-trinchera-boutique","status":"publish","type":"post","link":"https:\/\/lavaca.org\/trinchera\/marzo-2026-mu-trinchera-boutique\/","title":{"rendered":"Marzo en MU Trinchera Boutique"},"content":{"rendered":"<h1><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-89803 aligncenter\" src=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-11.38.55-819x1024.jpeg\" alt=\"\" width=\"819\" height=\"1024\" srcset=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-11.38.55-819x1024.jpeg 819w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-11.38.55-240x300.jpeg 240w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-11.38.55-768x960.jpeg 768w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-11.38.55-600x750.jpeg 600w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-11.38.55.jpeg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/h1>\n<h1>Primer Festival N\u00f3made Leer en casa \ud83d\udcd9 \u2763\ufe0f<\/h1>\n<p>\ud83d\udc49 Leer en Casa es un proyecto comunitario n\u00f3made que lleva el abrazo de la poes\u00eca a lo largo del continente.<\/p>\n<p>\ud83d\udd38\ufe0fYa ha recorrido m\u00e1s de 40 casas que abrieron sus puertas al festival de la palabra, organizado por las poetas Romina Funes (Argentina), Yirama Casta\u00f1o Guiza (Colombia) en alianza con Lely Carrasco (Cuba), An Cecil Portalet y Kayra Celasco (Argentina).<\/p>\n<p>\ud83d\udd38\ufe0f En esta oportunidad se suma la m\u00fasica de Susy Shock, Andrea Baz\u00e1n y Caro Bonillo.<\/p>\n<p>\ud83d\uddd3 Domingo 29 de marzo, 17 hs<br \/>\n\ud83c\udfe1 Riobamba 143, CABA<\/p>\n<p>A la gorra<br \/>\nReservas por <a href=\"https:\/\/publico.alternativateatral.com\/entradas100117-primer-festival-nomade-leer-en-casa?o=14\">Alternativa Teatral<\/a><\/p>\n<h1><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-89801 aligncenter\" src=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.34.08-710x1024.jpeg\" alt=\"\" width=\"710\" height=\"1024\" srcset=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.34.08-710x1024.jpeg 710w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.34.08-208x300.jpeg 208w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.34.08-768x1108.jpeg 768w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.34.08-600x866.jpeg 600w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.34.08.jpeg 887w\" sizes=\"auto, (max-width: 710px) 100vw, 710px\" \/><\/h1>\n<h1>TIEMPOS MODERNOS<br \/>\nCine en super 8 mm con m\u00fasica e vivo<\/h1>\n<p>\ud83d\udc49El Cineclub Mabuse emerge como un espacio de encuentro y resistencia cultural. Este proyecto -dedicado a proyecciones de cine en Super 8 mm, un formato f\u00edlmico que tuvo su auge hogare\u00f1o hasta mediados de los a\u00f1os 80 y que sigue encontrando nuevo material producido de los \u00faltimos treinta a\u00f1os,- es llevado adelante por Uriel Barros, programador y fundador del Cineclub Mabuse desde el 2001.<\/p>\n<p>\ud83d\udd38\ufe0fFunciona de manera itinerante, recorriendo distintos barrios y provincias del pa\u00eds, cada funci\u00f3n tiene una curadur\u00eda espec\u00edfica y un bono contribuci\u00f3n que ayuda a preservar y ampliar la colecci\u00f3n de material f\u00edlmico.<\/p>\n<p>\ud83d\udd38\ufe0fEn este primer encuentro cinematogr\u00e1fico en MU Trinchera Boutique, proyectaremos Tiempos modernos, el cl\u00e1sico de Charles Chaplin que sigue m\u00e1s vigente que nunca. El film ser\u00e1 proyectado en f\u00edlmico, en formato Super 8 mil\u00edmetros, en su versi\u00f3n completa de 4 rollos, con m\u00fasica compuesta e interpretada especialmente para la ocasi\u00f3n por el maestro Pablo Bronzini.<\/p>\n<p>\ud83d\uddd3 Sabado 28 d marzo, 21 hs<br \/>\n\ud83c\udfe1 Riobamba 143, CABA<\/p>\n<p>Entradas por <a href=\"https:\/\/publico.alternativateatral.com\/entradas99949-cine-en-super-8-mm-con-musica-en-vivo-tiempos-modernos?o=14\">Alternativa Teatral<\/a><\/p>\n<p>&nbsp;<\/p>\n<h1><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-89800 aligncenter\" src=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.33.14-819x1024.jpeg\" alt=\"\" width=\"819\" height=\"1024\" srcset=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.33.14-819x1024.jpeg 819w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.33.14-240x300.jpeg 240w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.33.14-768x960.jpeg 768w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.33.14-600x750.jpeg 600w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-13.33.14.jpeg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/h1>\n<h1>EN CLAVE DESOBEDIENTE<br \/>\nPresentaci\u00f3n del libro y charla<\/h1>\n<p>\ud83d\udc49En clave desobediente es una antolog\u00eda de textos de integrantes de la Asamblea Desobediente (Familiares de Genocidas por la Memoria, la Verdad y la Justicia).<\/p>\n<p>\ud83d\udd38\ufe0f A 50 a\u00f1os del.golpe civico-militar, se presenta esta obra colectiva que rompe silencios y construye memoria desde adentro de las familias.<\/p>\n<p>\ud83d\udd38\ufe0fLa Asamblea tambi\u00e9n lanza su p\u00e1gina web www.desobedecer.org, una herramienta para quienes buscan informaci\u00f3n sobre la posible participaci\u00f3n de sus familiares durante la dictadura.<\/p>\n<p>\ud83d\uddd3 Viernes 20 de diciembre, 19.30 hs<br \/>\n\ud83c\udfe1 Riobamba 143, CABA<\/p>\n<p>Reservas por <a href=\"https:\/\/publico.alternativateatral.com\/entradas99970-en-clave-desobediente?o=14\">Alternativa Teatral<\/a><\/p>\n<h1><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-89799 aligncenter\" src=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.33.07-835x1024.jpeg\" alt=\"\" width=\"835\" height=\"1024\" srcset=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.33.07-835x1024.jpeg 835w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.33.07-245x300.jpeg 245w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.33.07-768x942.jpeg 768w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.33.07-600x736.jpeg 600w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.33.07.jpeg 1044w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/h1>\n<h1>Teatro Documental<\/h1>\n<p>Por las calles de tierra de Monte Chingolo, en un barrio marginal del conurbano bonaerense. Un ciclista alcoh\u00f3lico, un hippie y un colectivero atraviesan la vida de una joven madre y sus hijas.<\/p>\n<p>Para la primavera Alfonsinista las drogas se consiguen en la farmacia y la jeringa se comparte. Una tarde un caballo aparece pastando en el fondo de la casa, pero \u00bfque hace ahi?. Fiestas de 15, las ranas que deja la inundaci\u00f3n y el rock como se baila en Chingolo.<\/p>\n<p>La noche antes de la muerte la madre presiente el peligro.<\/p>\n<p>30 a\u00f1os despu\u00e9s, la hermana intenta reconstruir la historia \u00bfQui\u00e9n era Sandra?.<\/p>\n<h1><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-89798 aligncenter\" src=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.31.05.jpeg\" alt=\"\" width=\"720\" height=\"823\" srcset=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.31.05.jpeg 720w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.31.05-262x300.jpeg 262w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.31.05-600x686.jpeg 600w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/h1>\n<h1>Escritos Sobrevivientes<\/h1>\n<p>A 50 a\u00f1os del golpe y en medio de aires negacionistas, la editorial lavaca pubica un nuevo libro, creado junto a un grupo de personas que estuvieron secuestradas y desaparecidas en distintos centros clandestinos de represi\u00f3n durante la \u00faltima dictadura militar.<\/p>\n<p>Escritos sobrevivientes compila una serie de textos producidos en un taller de escritura que tuvo lugar en MU durante 2024. Estos relatos abordan historias marcadas por lo que el grupo denomina \u00absubjetividad sobreviviente\u00bb. El resultado es un conjunto de textos po\u00e9ticos, pol\u00edticos y filos\u00f3ficos, de una potencia y belleza conmovedoras.<\/p>\n<p>As\u00ed lo resumen sus autoras y autores: \u00abUn grupo de compa\u00f1eras y compa\u00f1eros, ex detenidos desaparecidos por el terrorismo de Estado, nos reunimos en un taller de escritura para crear textos enfocados en la subjetividad sobreviviente, mientras la voz del poder alimenta el negacionismo y la reiteraci\u00f3n del sufrimiento popular por variados medios<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-89797 aligncenter\" src=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.18.03-820x1024.jpeg\" alt=\"\" width=\"820\" height=\"1024\" srcset=\"https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.18.03-820x1024.jpeg 820w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.18.03-240x300.jpeg 240w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.18.03-768x959.jpeg 768w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.18.03-1230x1536.jpeg 1230w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.18.03-600x750.jpeg 600w, https:\/\/lavaca.org\/trinchera\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-21.18.03.jpeg 1280w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><\/p>\n<h1>El Poeticazo<\/h1>\n<p>Si la sensaci\u00f3n es de arenas movedizas, esta noche de poes\u00eda y m\u00fasica en vivo ser\u00e1 un conjuro para erguirnos y sacudir el desaliento.<\/p>\n<p>BUENA VIBRA para la BUENA VIDA.<\/p>\n<p>La risa, la palabra y el abrazo como formas de resistencia. As\u00ed ser\u00e1 y all\u00ed nos vemos.<br \/>\nViernes 6 de marzo, 20.30 hs<br \/>\nRiobamba 143, CABA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primer Festival N\u00f3made Leer en casa \ud83d\udcd9 \u2763\ufe0f \ud83d\udc49 Leer en Casa es un proyecto comunitario n\u00f3made que lleva el abrazo de la poes\u00eca a lo largo del continente. \ud83d\udd38\ufe0fYa ha recorrido m\u00e1s de 40 casas que abrieron sus puertas al festival de la palabra, organizado por las poetas Romina Funes (Argentina), Yirama Casta\u00f1o Guiza (Colombia) en alianza con Lely [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[192],"tags":[196,193],"class_list":["post-89796","post","type-post","status-publish","format-standard","hentry","category-cartelera","tag-196","tag-cartelera"],"_links":{"self":[{"href":"https:\/\/lavaca.org\/trinchera\/wp-json\/wp\/v2\/posts\/89796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavaca.org\/trinchera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavaca.org\/trinchera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavaca.org\/trinchera\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lavaca.org\/trinchera\/wp-json\/wp\/v2\/comments?post=89796"}],"version-history":[{"count":3,"href":"https:\/\/lavaca.org\/trinchera\/wp-json\/wp\/v2\/posts\/89796\/revisions"}],"predecessor-version":[{"id":89805,"href":"https:\/\/lavaca.org\/trinchera\/wp-json\/wp\/v2\/posts\/89796\/revisions\/89805"}],"wp:attachment":[{"href":"https:\/\/lavaca.org\/trinchera\/wp-json\/wp\/v2\/media?parent=89796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavaca.org\/trinchera\/wp-json\/wp\/v2\/categories?post=89796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavaca.org\/trinchera\/wp-json\/wp\/v2\/tags?post=89796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}